{"id":155,"count":1,"description":"","link":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/","name":"lentos degumas","slug":"lentos-degumas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>lentos degumas - Hartika. Pi\u0119kno na lata.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archiwa: lentos degumas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hartika. Pi\u0119kno na lata.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hartika.com\/wp-content\/uploads\/2022\/12\/Tarasy_Kompozytowe_Hartika801.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/\",\"url\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/\",\"name\":\"lentos degumas - Hartika. Pi\u0119kno na lata.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/hartika.com\\\/lt\\\/strona-glowna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"lentos degumas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/hartika.com\\\/lt\\\/\",\"name\":\"Tarasy i ogrodzenia kompozytowe Hartika. Pi\u0119kno na lata.\",\"description\":\"Producent taras\u00f3w i ogrodze\u0144 kompozytowych.\",\"publisher\":{\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/#organization\"},\"alternateName\":\"Tarasy i ogrodzenia kompozytowe Hartika.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hartika.com\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":[\"Organization\",\"Place\",\"Corporation\"],\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/#organization\",\"name\":\"Hartika Sp. z o.o.\",\"alternateName\":\"Hartika WPC\",\"url\":\"https:\\\/\\\/hartika.com\\\/lt\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Tarasy-Hartika\\\/100057582753952\\\/\",\"https:\\\/\\\/ke.linkedin.com\\\/company\\\/hartika\"],\"address\":{\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"53.55530067584501\",\"longitude\":\"22.309762340482035\"},\"telephone\":[\"+48864442020\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"08:00\",\"closes\":\"16:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"}],\"email\":\"hartika@hartika.com\",\"areaServed\":\"Europa\",\"vatID\":\"PL5423070660\",\"taxID\":\"5423070660\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#local-main-place-address\",\"streetAddress\":\"ul. Przemys\u0142owa 9\",\"addressLocality\":\"Szczuczyn\",\"postalCode\":\"19-230\",\"addressRegion\":\"Podlaskie\",\"addressCountry\":\"PL\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/hartika.com\\\/lt\\\/tag\\\/lentos-degumas\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/hartika.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/LOGO.svg\",\"contentUrl\":\"https:\\\/\\\/hartika.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/LOGO.svg\",\"caption\":\"Hartika Sp. z o.o.\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Szczuczyn\" \/>\n<meta name=\"geo.position\" content=\"53.55530067584501;22.309762340482035\" \/>\n<meta name=\"geo.region\" content=\"Poland\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lentos degumas - Hartika. Pi\u0119kno na lata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/","og_locale":"lt_LT","og_type":"article","og_title":"Archiwa: lentos degumas","og_url":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/","og_site_name":"Hartika. Pi\u0119kno na lata.","og_image":[{"width":800,"height":534,"url":"https:\/\/hartika.com\/wp-content\/uploads\/2022\/12\/Tarasy_Kompozytowe_Hartika801.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/","url":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/","name":"lentos degumas - Hartika. Pi\u0119kno na lata.","isPartOf":{"@id":"https:\/\/hartika.com\/lt\/#website"},"breadcrumb":{"@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#breadcrumb"},"inLanguage":"lt-LT"},{"@type":"BreadcrumbList","@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/hartika.com\/lt\/strona-glowna\/"},{"@type":"ListItem","position":2,"name":"lentos degumas"}]},{"@type":"WebSite","@id":"https:\/\/hartika.com\/lt\/#website","url":"https:\/\/hartika.com\/lt\/","name":"Tarasy i ogrodzenia kompozytowe Hartika. Pi\u0119kno na lata.","description":"Producent taras\u00f3w i ogrodze\u0144 kompozytowych.","publisher":{"@id":"https:\/\/hartika.com\/lt\/#organization"},"alternateName":"Tarasy i ogrodzenia kompozytowe Hartika.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hartika.com\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":["Organization","Place","Corporation"],"@id":"https:\/\/hartika.com\/lt\/#organization","name":"Hartika Sp. z o.o.","alternateName":"Hartika WPC","url":"https:\/\/hartika.com\/lt\/","logo":{"@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#local-main-organization-logo"},"image":{"@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/people\/Tarasy-Hartika\/100057582753952\/","https:\/\/ke.linkedin.com\/company\/hartika"],"address":{"@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"53.55530067584501","longitude":"22.309762340482035"},"telephone":["+48864442020","+48864442020"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday"],"opens":"08:00","closes":"16:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday","Sunday"],"opens":"00:00","closes":"00:00"}],"email":"hartika@hartika.com","areaServed":"Europa","vatID":"PL5423070660","taxID":"5423070660"},{"@type":"PostalAddress","@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#local-main-place-address","streetAddress":"ul. Przemys\u0142owa 9","addressLocality":"Szczuczyn","postalCode":"19-230","addressRegion":"Podlaskie","addressCountry":"PL"},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/hartika.com\/lt\/tag\/lentos-degumas\/#local-main-organization-logo","url":"https:\/\/hartika.com\/wp-content\/uploads\/2019\/10\/LOGO.svg","contentUrl":"https:\/\/hartika.com\/wp-content\/uploads\/2019\/10\/LOGO.svg","caption":"Hartika Sp. z o.o."}]},"geo.placename":"Szczuczyn","geo.position":{"lat":"53.55530067584501","long":"22.309762340482035"},"geo.region":"Poland"},"_links":{"self":[{"href":"https:\/\/hartika.com\/lt\/wp-json\/wp\/v2\/tags\/155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hartika.com\/lt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hartika.com\/lt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hartika.com\/lt\/wp-json\/wp\/v2\/posts?tags=155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}